{"id":13363,"date":"2024-08-24T00:21:28","date_gmt":"2024-08-23T22:21:28","guid":{"rendered":"https:\/\/digi.hosting\/?post_type=docs&#038;p=13363"},"modified":"2025-01-09T20:37:58","modified_gmt":"2025-01-09T19:37:58","password":"","slug":"estructura-del-directorio","status":"publish","type":"docs","link":"https:\/\/digi.hosting\/es\/support\/mappen-structuur\/","title":{"rendered":"Estructura de las carpetas"},"content":{"rendered":"<p>Antes de empezar a subir su sitio web, es importante saber qu\u00e9 funci\u00f3n tiene cada carpeta en su paquete de alojamiento. Te lo explicamos a continuaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"directory-structure\">General<\/h3>\n\n\n\n<p>Cuando vayas al Gestor de Archivos o te conectes v\u00eda FTP encontrar\u00e1s las siguientes carpetas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\/reservas<\/li>\n\n\n\n<li>\/dominios<\/li>\n\n\n\n<li>\/imap<\/li>\n\n\n\n<li>\/Maildir<\/li>\n\n\n\n<li>\/public_html<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"backups\">\/reservas<\/h4>\n\n\n\n<p>La carpeta \/backups contiene todas las copias de seguridad creadas a trav\u00e9s de DirectAdmin. No tendr\u00e1 una carpeta \/backups hasta que cree una copia de seguridad en el panel de control.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"domains\">\/dominios<\/h4>\n\n\n\n<p>La carpeta \/dominios contiene los archivos relacionados con su(s) cuenta(s) de alojamiento. Cada dominio alojado en su cuenta tiene su propia carpeta (\/dominios\/miweb.com). Esa carpeta contiene:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\/logs<\/li>\n\n\n\n<li>\/private_html<\/li>\n\n\n\n<li>\/public_html (Aqu\u00ed es donde subes tu sitio web)<\/li>\n\n\n\n<li>\/ftp_p\u00fablico<\/li>\n\n\n\n<li>\/estad\u00edstica<\/li>\n\n\n\n<li>\/Maildir<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"imap\">\/imap<\/h4>\n\n\n\n<p>La carpeta IMAP contiene datos relacionados con tus direcciones de correo electr\u00f3nico. As\u00ed que es mejor no cambiar nada de esta carpeta ni de su contenido.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"maildir\">\/Maildir<\/h4>\n\n\n\n<p>\/Maildir es el almac\u00e9n de buzones de correo electr\u00f3nico del sistema. No tiene nada que ver con los buzones virtuales. En la mayor\u00eda de los casos, la carpeta contiene errores y notificaciones del sistema.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"public-html\">\/public_html<\/h4>\n\n\n\n<p>En \/public_html subes los datos de tu sitio web. Aseg\u00farate de poner los datos en la carpeta public_html correcta si tienes varios nombres de dominio vinculados a tu alojamiento web. Lo mejor es navegar a \/dominios\/miweb.com\/public_html para trabajar en la carpeta correcta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"home-index-html-file\">archivo index.html<\/h3>\n\n\n\n<p>El archivo por defecto de cualquier directorio web es index.html. Esto significa que cuando los visitantes visitan https:\/\/www.mywebsite.com, el servidor en realidad los env\u00eda a https:\/\/www.mywebsite.com\/index.html. Esto funciona para cualquier directorio de acceso p\u00fablico de su sistema, incluidos los subdominios.<\/p>\n\n\n\n<p>Recuerde renombrar o borrar este index.html cuando suba su sitio web. Los usuarios avanzados pueden utilizar archivos PHP, archivos shtml, etc.<\/p>","protected":false},"excerpt":{"rendered":"<p>Voor je aan de slag gaat met het uploaden van je website is het belangrijk om te weten welke functie elke map heeft in jouw hostingpakket. We leggen het hieronder uit. Algemeen Wanneer u naar de File Manager gaat of verbind via FTP vind u de volgende mappen terug: \/back-ups De \/backups map bevat alle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"doc_category":[70],"glossaries":[],"doc_tag":[],"knowledge_base":[75],"class_list":["post-13363","docs","type-docs","status-publish","hentry","doc_category-upload-je-website","knowledge_base-directadmin-webhosting"],"acf":[],"year_month":"2026-07","word_count":300,"total_views":"1452","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"admindigihosting","author_nicename":"admindigihosting","author_url":"https:\/\/digi.hosting\/es\/author\/admindigihosting\/"},"doc_category_info":[{"term_name":"Upload je website","term_url":"https:\/\/digi.hosting\/es\/support\/directadmin-webhosting\/upload-je-website\/"}],"doc_tag_info":[],"knowledge_base_info":[{"term_name":"DirectAdmin Webhosting","term_url":"https:\/\/digi.hosting\/es\/support\/directadmin-webhosting\/","term_slug":"directadmin-webhosting"}],"knowledge_base_slug":["directadmin-webhosting"],"_links":{"self":[{"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/docs\/13363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/comments?post=13363"}],"version-history":[{"count":1,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/docs\/13363\/revisions"}],"predecessor-version":[{"id":13364,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/docs\/13363\/revisions\/13364"}],"wp:attachment":[{"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/media?parent=13363"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/doc_category?post=13363"},{"taxonomy":"glossaries","embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/glossaries?post=13363"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/doc_tag?post=13363"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/digi.hosting\/es\/wp-json\/wp\/v2\/knowledge_base?post=13363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}